{"id":177,"date":"2023-10-11T17:47:08","date_gmt":"2023-10-11T15:47:08","guid":{"rendered":"https:\/\/bdese.emalti-rh.fr\/?page_id=177"},"modified":"2023-10-11T17:47:08","modified_gmt":"2023-10-11T15:47:08","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/","title":{"rendered":"mentions l\u00e9gales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">d\u00e9couvrez nos mentions l\u00e9gales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Site officiel d\u2019Emalti-RH : <a href=\"https:\/\/www.emalti-rh.com\/\">https:\/\/www.emalti-rh.com\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si\u00e8ge : 136 Rue de la Sous-Pr\u00e9fecture, 69400 Villefranche-sur-Sa\u00f4ne<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00e9l\u00e9phone : 04.74.07.99.82<br>Email : contact@trdeveloppement.fr<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conception et r\u00e9alisation : TR DEVELOPPEMENT<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9bergement : OVH<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9daction, publication, animation et gestion \u00e9ditoriale : Emalti-RH<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PROTECTION DES DONN\u00c9ES A CARACT\u00c8RE PERSONNEL<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Emalti-RH s\u2019engage \u00e0 ce que la collecte et le traitement de vos donn\u00e9es soient conformes au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) et \u00e0 la loi Informatique et Libert\u00e9s, modifi\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es personnelles collect\u00e9es sur ce site sont destin\u00e9es aux services communautaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous b\u00e9n\u00e9ficiez d\u2019un droit d\u2019acc\u00e8s, de rectification, de portabilit\u00e9, d\u2019effacement de celles-ci ou une limitation de traitement.<br>Vous pouvez vous opposer au traitement des donn\u00e9es vous concernant et disposez du droit de retirer votre consentement \u00e0 tout moment en vous adressant \u00e0 contact@trdeveloppement.fr ou par courrier TR D\u00e9veloppement, 136 Rue de la Sous-Pr\u00e9fecture, 69400 Villefranche-sur-Sa\u00f4ne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces demandes doivent \u00eatre accompagn\u00e9es de la copie d\u2019un titre d\u2019identit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le cas \u00e9ch\u00e9ant, vous avez la possibilit\u00e9 d\u2019introduire une r\u00e9clamation aupr\u00e8s de la CNIL (<a href=\"http:\/\/www.cnil.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.cnil.fr<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les informations que Emalti-RH est amen\u00e9 \u00e0 recueillir proviennent de leur communication volontaire par les personnes physiques par saisie sur les formulaires en ligne. La destination des informations collect\u00e9es est pr\u00e9cis\u00e9e sur chaque formulaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les informations nominatives sont exclusivement collect\u00e9es pour un usage interne, non commercial, et elles ne pourront faire l\u2019objet d\u2019aucune transmission \u00e0 un tiers.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UTILISATION DE COOKIES<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un cookie est un petit fichier informatique, un traceur. Il permet d\u2019analyser le comportement des usagers lors de leur visite du site internet d\u2019Emalti-RH.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cookies de ce site sont utilis\u00e9s par le syst\u00e8me de statistiques Google Analytics et par le syst\u00e8me de gestion de contenu du site.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aucune information nominative n\u2019est enregistr\u00e9e.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PROPRI\u00c9T\u00c9 INTELLECTUELLE<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le pr\u00e9sent site est une \u0153uvre de Emalti-RH au sens des articles L111-1 et suivants du Code de la propri\u00e9t\u00e9 intellectuelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les photographies, textes, logos, pictogrammes ainsi que toute \u0153uvre int\u00e9gr\u00e9e dans le site sont la propri\u00e9t\u00e9 d\u2019Emalti-RH ou de tiers ayant autoris\u00e9 Emalti-RH \u00e0 les utiliser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les reproductions, les transmissions, les modifications, les r\u00e9utilisations, sur un support papier ou informatique du site et des \u0153uvres qui y sont reproduites ne sont autoris\u00e9es que pour un usage personnel et priv\u00e9 conforme aux dispositions de l\u2019article L122-5 du Code de la propri\u00e9t\u00e9 intellectuelle.<br>Les reproductions, les transmissions, les modifications, les r\u00e9utilisations \u00e0 des fins publicitaires, commerciales ou d\u2019information, de tout ou partie du site sont interdites.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LIENS VERS DES SITES TIERS DEPUIS LE SITE<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les liens hypertextes mis en \u0153uvre au sein du site en direction d\u2019autres sites et d\u2019une mani\u00e8re g\u00e9n\u00e9rale vers toutes ressources existantes sur internet ne sauraient engager la responsabilit\u00e9 d\u2019Emalti-RH quant aux liens qu\u2019ils contiennent ou aux mises \u00e0 jour qui leur sont apport\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">contact@trdeveloppement.fr<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>d\u00e9couvrez nos mentions l\u00e9gales Site officiel d\u2019Emalti-RH : https:\/\/www.emalti-rh.com\/ Si\u00e8ge : 136 Rue de la Sous-Pr\u00e9fecture, 69400 Villefranche-sur-Sa\u00f4ne T\u00e9l\u00e9phone : 04.74.07.99.82Email : contact@trdeveloppement.fr Conception et r\u00e9alisation : TR DEVELOPPEMENT H\u00e9bergement : OVH R\u00e9daction, publication, animation et gestion \u00e9ditoriale : Emalti-RH PROTECTION DES DONN\u00c9ES A CARACT\u00c8RE PERSONNEL Emalti-RH s\u2019engage \u00e0 ce que la collecte et le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-177","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>mentions l\u00e9gales - BDESE par Emalti-RH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mentions l\u00e9gales\" \/>\n<meta property=\"og:description\" content=\"d\u00e9couvrez nos mentions l\u00e9gales Site officiel d\u2019Emalti-RH : https:\/\/www.emalti-rh.com\/ Si\u00e8ge : 136 Rue de la Sous-Pr\u00e9fecture, 69400 Villefranche-sur-Sa\u00f4ne T\u00e9l\u00e9phone : 04.74.07.99.82Email : contact@trdeveloppement.fr Conception et r\u00e9alisation : TR DEVELOPPEMENT H\u00e9bergement : OVH R\u00e9daction, publication, animation et gestion \u00e9ditoriale : Emalti-RH PROTECTION DES DONN\u00c9ES A CARACT\u00c8RE PERSONNEL Emalti-RH s\u2019engage \u00e0 ce que la collecte et le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/\" \/>\n<meta property=\"og:site_name\" content=\"BDESE par Emalti-RH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/index.php\\\/mentions-legales\\\/\",\"url\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/index.php\\\/mentions-legales\\\/\",\"name\":\"mentions l\u00e9gales - BDESE par Emalti-RH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/#website\"},\"datePublished\":\"2023-10-11T15:47:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/index.php\\\/mentions-legales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bdese.emalti-rh.fr\\\/index.php\\\/mentions-legales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/index.php\\\/mentions-legales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/#website\",\"url\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/\",\"name\":\"BDESE par Emalti-RH\",\"description\":\"diffusez simplement et rapidement votre BDESE\",\"publisher\":{\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/#organization\",\"name\":\"Emalti-RH\",\"url\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/bdese.emalti-rh.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/emaltiRH-594x205-1.png\",\"contentUrl\":\"http:\\\/\\\/bdese.emalti-rh.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/emaltiRH-594x205-1.png\",\"width\":594,\"height\":205,\"caption\":\"Emalti-RH\"},\"image\":{\"@id\":\"https:\\\/\\\/bdese.emalti-rh.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tr-developpement-sas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"mentions l\u00e9gales - BDESE par Emalti-RH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/","og_locale":"fr_FR","og_type":"article","og_title":"mentions l\u00e9gales","og_description":"d\u00e9couvrez nos mentions l\u00e9gales Site officiel d\u2019Emalti-RH : https:\/\/www.emalti-rh.com\/ Si\u00e8ge : 136 Rue de la Sous-Pr\u00e9fecture, 69400 Villefranche-sur-Sa\u00f4ne T\u00e9l\u00e9phone : 04.74.07.99.82Email : contact@trdeveloppement.fr Conception et r\u00e9alisation : TR DEVELOPPEMENT H\u00e9bergement : OVH R\u00e9daction, publication, animation et gestion \u00e9ditoriale : Emalti-RH PROTECTION DES DONN\u00c9ES A CARACT\u00c8RE PERSONNEL Emalti-RH s\u2019engage \u00e0 ce que la collecte et le [&hellip;]","og_url":"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/","og_site_name":"BDESE par Emalti-RH","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/","url":"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/","name":"mentions l\u00e9gales - BDESE par Emalti-RH","isPartOf":{"@id":"https:\/\/bdese.emalti-rh.fr\/#website"},"datePublished":"2023-10-11T15:47:08+00:00","breadcrumb":{"@id":"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bdese.emalti-rh.fr\/index.php\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bdese.emalti-rh.fr\/"},{"@type":"ListItem","position":2,"name":"mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/bdese.emalti-rh.fr\/#website","url":"https:\/\/bdese.emalti-rh.fr\/","name":"BDESE par Emalti-RH","description":"diffusez simplement et rapidement votre BDESE","publisher":{"@id":"https:\/\/bdese.emalti-rh.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bdese.emalti-rh.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bdese.emalti-rh.fr\/#organization","name":"Emalti-RH","url":"https:\/\/bdese.emalti-rh.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bdese.emalti-rh.fr\/#\/schema\/logo\/image\/","url":"http:\/\/bdese.emalti-rh.fr\/wp-content\/uploads\/2023\/10\/emaltiRH-594x205-1.png","contentUrl":"http:\/\/bdese.emalti-rh.fr\/wp-content\/uploads\/2023\/10\/emaltiRH-594x205-1.png","width":594,"height":205,"caption":"Emalti-RH"},"image":{"@id":"https:\/\/bdese.emalti-rh.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/tr-developpement-sas\/"]}]}},"_links":{"self":[{"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/pages\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":1,"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/pages\/177\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/pages\/177\/revisions\/178"}],"wp:attachment":[{"href":"https:\/\/bdese.emalti-rh.fr\/index.php\/wp-json\/wp\/v2\/media?parent=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}